
{"id":145,"date":"2015-02-03T20:50:06","date_gmt":"2015-02-03T20:50:06","guid":{"rendered":"http:\/\/new.hotel-oxo.com\/?page_id=145"},"modified":"2017-10-14T12:45:06","modified_gmt":"2017-10-14T12:45:06","slug":"guia-y-ocio","status":"publish","type":"page","link":"https:\/\/www.hotel-oxo.com\/es\/guia-y-ocio\/","title":{"rendered":"Gu\u00eda y ocio"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]De nuestras referencias en los mejores guias pasando por nuestras sugerencias para aprovechar del mejor de todas las actividades que ofrecen Biarritz y sus alrededores, le desean buenos momentos de descanso y degustaciones.<\/p>\n<h1>Que hacer en Biarritz<\/h1>\n<p><b><a href=\"\/wp-content\/uploads\/2015\/02\/loisirs.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-105\" src=\"\/wp-content\/uploads\/2015\/02\/loisirs-219x300.jpg\" alt=\"loisirs\" width=\"219\" height=\"300\" \/><\/a>Un d\u00eda en Biarritz<\/b><\/p>\n<p>Visitar la ciudad, sus jardines, sus playas.<br \/>\nIr a lo largo del mar, admirar los panoramas del faro y de la costa Vasca pasando por la gran playa, descubrir los \u00abcrampottes\u00bb de los pescadores al Puerto-viejo, y alimentar a las focas en el museo del mar. Iniciarse en el golf o el surf. Errar sobre la senda del litoral, contemplando el oceano, Bidart y Gu\u00e9thary. Sacar provecho de numerosas exposiciones a lo largo del ano, espectaculos a la \u00abGare du Midi\u00bb, del casino y de los festivales.<\/p>\n<p><b>Dos d\u00edas en Biarritz<\/b><\/p>\n<p>Ofrecerse un instantane de descanso en uno de los numerosos centros de talasoterapia. Visitar los pueblos vascos tipicos A\u00efnhoa, Espelette, Itxassu, Sare, Zuggaramurdi. Descubrir Bayonne, su catedral, sus museos y sus viejos cuartos.<br \/>\nSubir la Rhune en tren o a pie y sacar provecho de su panorama. Desde Hendaye, atravesar la Bidassoa en barco para ir a comer tapas en Fontarrabie.<\/p>\n<p><b>Tres d\u00edas en Biarritz<\/b><\/p>\n<p>Pasearse en Anglet en el bosque de Chiberta o en la Habitacion de Amor. Descubrir Saint Jean de Luz su arquitectura, su bahia protegida de las olas. Pasearse en Saint Jean Pied de Port, su ciudadela, la puerta Santiago, catar los vinos de Iruleguy. Ir a San Sebastian y en sus bares a pinchos.<br \/>\n<b>Estancia larga<\/b><\/p>\n<p>Reposarse en el momento de una estancia de talasoterapia. Perfeccionar su tecnica de surf o perfeccionar su swing de golf segun practicas en Biarritz. Recorrer a Bilboa y visitar el museo Guggenheim.<\/p>\n<p>Para mas informaciones, gracias por consultar : <a class=\"menu\" href=\"http:\/\/www.biarritz.fr\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.biarritz.fr<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]De nuestras referencias en los mejores guias pasando por nuestras sugerencias para aprovechar del mejor de todas las actividades que ofrecen Biarritz y sus alrededores, le desean buenos momentos de descanso y degustaciones. Que hacer en Biarritz Un d\u00eda en Biarritz Visitar la ciudad, sus jardines, sus playas. Ir a lo largo del mar, admirar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-145","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/pages\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":4,"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/pages\/145\/revisions"}],"predecessor-version":[{"id":590,"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/pages\/145\/revisions\/590"}],"wp:attachment":[{"href":"https:\/\/www.hotel-oxo.com\/es\/wp-json\/wp\/v2\/media?parent=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}